{"id":3214,"count":1,"description":"","link":"https:\/\/www.booktopia.com.au\/blog\/tag\/lets-pretend-this-never-happened\/","name":"Let's Pretend This Never Happened","slug":"lets-pretend-this-never-happened","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.booktopia.com.au\/blog\/wp-json\/wp\/v2\/tags\/3214"}],"collection":[{"href":"https:\/\/www.booktopia.com.au\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.booktopia.com.au\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.booktopia.com.au\/blog\/wp-json\/wp\/v2\/posts?tags=3214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}